{"id":358,"date":"2024-05-16T19:24:51","date_gmt":"2024-05-16T19:24:51","guid":{"rendered":"https:\/\/panairllc.com\/?post_type=partner&#038;p=358"},"modified":"2024-05-17T19:09:37","modified_gmt":"2024-05-17T19:09:37","slug":"aligned-vision","status":"publish","type":"partner","link":"https:\/\/panairllc.com\/pt\/partner\/aligned-vision\/","title":{"rendered":"Aligned Vision"},"content":{"rendered":"<p><strong><em>Aligned Vision<\/em><\/strong>, anteriormente Assembly Guidance Systems, foi fundada em 1988 para desenvolver, fornecer e dar suporte ao uso de lasers para exibir dados 3D em sistemas aut\u00f4nomos e integrados para aumentar a produtividade manual.<\/p>","protected":false},"featured_media":31,"template":"","categoty-partners":[10,14,21,43],"class_list":["post-358","partner","type-partner","status-publish","has-post-thumbnail","hentry","categoty-partners-aviation-oem","categoty-partners-space-defense","categoty-partners-support-equipment-aviation-oem","categoty-partners-support-equipment-space-defense"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aligned Vision - Panair LLC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/panairllc.com\/pt\/partner\/aligned-vision\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aligned Vision - Panair LLC\" \/>\n<meta property=\"og:description\" content=\"Aligned Vision, formerly Assembly Guidance Systems, was founded in 1988 to develop, deliver, and support the use of lasers to display 3D data in stand\u2013alone and integrated systems to enhance manual productivity.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/panairllc.com\/pt\/partner\/aligned-vision\/\" \/>\n<meta property=\"og:site_name\" content=\"Panair LLC\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-17T19:09:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/05\/aligned-vision.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"472\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/\",\"url\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/\",\"name\":\"Aligned Vision - Panair LLC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/panairllc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/panairllc.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/aligned-vision.jpg\",\"datePublished\":\"2024-05-16T19:24:51+00:00\",\"dateModified\":\"2024-05-17T19:09:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/#primaryimage\",\"url\":\"https:\\\/\\\/panairllc.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/aligned-vision.jpg\",\"contentUrl\":\"https:\\\/\\\/panairllc.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/aligned-vision.jpg\",\"width\":472,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/panairllc.com\\\/partner\\\/aligned-vision\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/panairllc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partners\",\"item\":\"https:\\\/\\\/panairllc.com\\\/partners\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aligned Vision\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/panairllc.com\\\/#website\",\"url\":\"https:\\\/\\\/panairllc.com\\\/\",\"name\":\"Panair LLC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/panairllc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/panairllc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/panairllc.com\\\/#organization\",\"name\":\"Panair LLC\",\"url\":\"https:\\\/\\\/panairllc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/panairllc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/panairllc.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/panairllc_logo.jpeg\",\"contentUrl\":\"https:\\\/\\\/panairllc.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/panairllc_logo.jpeg\",\"width\":200,\"height\":200,\"caption\":\"Panair LLC\"},\"image\":{\"@id\":\"https:\\\/\\\/panairllc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/panairllc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aligned Vision - Panair LLC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/panairllc.com\/pt\/partner\/aligned-vision\/","og_locale":"pt_BR","og_type":"article","og_title":"Aligned Vision - Panair LLC","og_description":"Aligned Vision, formerly Assembly Guidance Systems, was founded in 1988 to develop, deliver, and support the use of lasers to display 3D data in stand\u2013alone and integrated systems to enhance manual productivity.","og_url":"https:\/\/panairllc.com\/pt\/partner\/aligned-vision\/","og_site_name":"Panair LLC","article_modified_time":"2024-05-17T19:09:37+00:00","og_image":[{"width":472,"height":200,"url":"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/05\/aligned-vision.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/panairllc.com\/partner\/aligned-vision\/","url":"https:\/\/panairllc.com\/partner\/aligned-vision\/","name":"Aligned Vision - Panair LLC","isPartOf":{"@id":"https:\/\/panairllc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/panairllc.com\/partner\/aligned-vision\/#primaryimage"},"image":{"@id":"https:\/\/panairllc.com\/partner\/aligned-vision\/#primaryimage"},"thumbnailUrl":"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/05\/aligned-vision.jpg","datePublished":"2024-05-16T19:24:51+00:00","dateModified":"2024-05-17T19:09:37+00:00","breadcrumb":{"@id":"https:\/\/panairllc.com\/partner\/aligned-vision\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/panairllc.com\/partner\/aligned-vision\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/panairllc.com\/partner\/aligned-vision\/#primaryimage","url":"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/05\/aligned-vision.jpg","contentUrl":"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/05\/aligned-vision.jpg","width":472,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/panairllc.com\/partner\/aligned-vision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/panairllc.com\/"},{"@type":"ListItem","position":2,"name":"Partners","item":"https:\/\/panairllc.com\/partners\/"},{"@type":"ListItem","position":3,"name":"Aligned Vision"}]},{"@type":"WebSite","@id":"https:\/\/panairllc.com\/#website","url":"https:\/\/panairllc.com\/","name":"Panair LLC","description":"","publisher":{"@id":"https:\/\/panairllc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/panairllc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/panairllc.com\/#organization","name":"Panair LLC","url":"https:\/\/panairllc.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/panairllc.com\/#\/schema\/logo\/image\/","url":"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/08\/panairllc_logo.jpeg","contentUrl":"https:\/\/panairllc.com\/wp-content\/uploads\/2024\/08\/panairllc_logo.jpeg","width":200,"height":200,"caption":"Panair LLC"},"image":{"@id":"https:\/\/panairllc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/panairllc"]}]}},"_links":{"self":[{"href":"https:\/\/panairllc.com\/pt\/wp-json\/wp\/v2\/partner\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panairllc.com\/pt\/wp-json\/wp\/v2\/partner"}],"about":[{"href":"https:\/\/panairllc.com\/pt\/wp-json\/wp\/v2\/types\/partner"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/panairllc.com\/pt\/wp-json\/wp\/v2\/media\/31"}],"wp:attachment":[{"href":"https:\/\/panairllc.com\/pt\/wp-json\/wp\/v2\/media?parent=358"}],"wp:term":[{"taxonomy":"categoty-partners","embeddable":true,"href":"https:\/\/panairllc.com\/pt\/wp-json\/wp\/v2\/categoty-partners?post=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}